{"id":3,"date":"2021-11-17T09:46:47","date_gmt":"2021-11-17T09:46:47","guid":{"rendered":"https:\/\/chrispeluqueria.com\/?page_id=3"},"modified":"2021-12-02T09:02:20","modified_gmt":"2021-12-02T09:02:20","slug":"politica-privacidad","status":"publish","type":"page","link":"https:\/\/chrispeluqueria.com\/index.php\/politica-privacidad\/","title":{"rendered":"Aviso Legal y Pol\u00edtica de privacidad"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">INTRODUCCI\u00d3N.<\/h2>\r\n<p>El presente documento tiene como finalidad el establecer y regular las normas de uso del Sitio www.chrispeluqueria.com entendiendo por Sitio todas las p\u00e1ginas y sus contenidos propiedad de CRISTINA LUNA a las cuales se accede a trav\u00e9s del dominio www.chrispeluqueria.com\u00a0y sus subdominios. La utilizaci\u00f3n del Sitio atribuye la condici\u00f3n de Usuario del mismo e implica la aceptaci\u00f3n de todas las condiciones incluidas en el presente Aviso Legal.<\/p>\r\n<p>El Usuario se compromete a leer atentamente el presente Aviso Legal en cada una de las ocasiones en que se proponga utilizar el Sitio, ya que \u00e9ste y sus condiciones de uso recogidas en el presente Aviso Legal pueden sufrir modificaciones.<\/p>\r\n<h2>TITULARIDAD DEL SITIO WEB.<\/h2>\r\n<p>El titular del presente Sitio es CRISTINA LUNA\u00a0 con domicilio en AVENIDA MARTINEZ DE VELASCO 1, LOCAL 3 &#8211; HUESCA 22005 y NIF: 47931457D<\/p>\r\n<p>Ud. puede ponerse en contacto con nosotros en el siguiente n\u00famero de tel\u00e9fono <span aria-label=\"Llamar al n\u00famero de tel\u00e9fono 974 09 90 90\">974 09 90 90<\/span>\u00a0 e-mail: <a href=\"mailto:hola@chrispeluqueria.com\">hola@chrispeluqueria.com<\/a><\/p>\r\n<h2>PROPIEDAD INTELECTUAL E INDUSTRIAL.<\/h2>\r\n<p>Los derechos de propiedad intelectual de este Sitio, son titularidad de CRISTINA LUNA.<\/p>\r\n<p>La reproducci\u00f3n, distribuci\u00f3n, comercializaci\u00f3n o transformaci\u00f3n, total o parcial, no autorizadas del contenido del Sitio, a no ser que sea para uso personal y privado, constituye una infracci\u00f3n de los derechos de propiedad intelectual de CRISTINA LUNA. Igualmente, todas las marcas o signos distintivos de cualquier clase contenidos en el Sitio est\u00e1n protegidos por Ley. La utilizaci\u00f3n no autorizada de la informaci\u00f3n contenida en este Sitio, as\u00ed como los perjuicios ocasionados en los derechos de propiedad intelectual e industrial de CRISTINA LUNA, pueden dar lugar al ejercicio de las acciones que legalmente correspondan y, si procede, a las responsabilidades que de dicho ejercicio se deriven.<\/p>\r\n<h2>EXCLUSI\u00d3N DE RESPONSABILIDAD.<\/h2>\r\n<p>El contenido, fotograf\u00edas, programas y\/o informaci\u00f3n expresados en este Sitio deben entenderse como simplemente orientativos. CRISTINA LUNA, no responde de ninguna forma de la efectividad o exactitud de los mismos, quedando exenta de cualquier responsabilidad contractual o extra contractual con los Usuarios que haga uso de ellos, ya que son \u00e9stas las que deber\u00e1n decidir seg\u00fan su criterio la oportunidad de los mismos.<\/p>\r\n<p>En este Sitio se pueden publicar contenidos aportados por terceras personas o empresas, CRISTINA LUNA no responde de la veracidad y exactitud de los mismos, quedando exento de cualquier responsabilidad contractual o extracontractual con los Usuarios que hagan uso de ellos.<\/p>\r\n<p>CRISTINA LUNA, se reserva el derecho de modificar el contenido del Sitio sin previo aviso y sin ning\u00fan tipo de limitaci\u00f3n.<\/p>\r\n<p>Asimismo, declina cualquier responsabilidad por los eventuales da\u00f1os y perjuicios que puedan ocasionarse por la falta de disponibilidad y\/o continuidad de este Sitio y de los servicios que se ofrecen en \u00e9l.<\/p>\r\n<p>CRISTINA LUNA, no garantiza la ausencia de virus ni de otros elementos en la web que puedan producir alteraciones en su sistema inform\u00e1tico CRISTINA LUNA, declina cualquier responsabilidad contractual o extracontractual con los Usuarios que hagan uso de ello y tuviera perjuicios de cualquier naturaleza ocasionados por virus inform\u00e1ticos o por elementos inform\u00e1ticos de cualquier \u00edndole.<\/p>\r\n<h2>PROTECCI\u00d3N DE DATOS DE CAR\u00c1CTER PERSONAL.<\/h2>\r\n<p>En CRISTINA LUNA tratamos la informaci\u00f3n que nos facilita con el fin de prestarles el servicio solicitado y realizar su facturaci\u00f3n. Los datos proporcionados se conservar\u00e1n mientras se mantenga la relaci\u00f3n comercial o durante el tiempo necesario para cumplir con las obligaciones legales y atender las posibles responsabilidades que pudieran derivar del cumplimiento de la finalidad para la que los datos fueron recabados. Los datos no se ceder\u00e1n a terceros salvo en los casos en que exista una obligaci\u00f3n legal. Usted tiene derecho a obtener informaci\u00f3n sobre si en CRISTINA LUNA estamos tratando sus datos personales, por lo que puede ejercer sus derechos de acceso, rectificaci\u00f3n, supresi\u00f3n y portabilidad de datos y oposici\u00f3n y limitaci\u00f3n a su tratamiento ante CRISTINA LUNA, AVENIDA MARTINEZ DE VELASCO 1, LOCAL 3 &#8211; HUESCA 22005 o en la direcci\u00f3n de correo electr\u00f3nico hola@chrispeluqueria.com, adjuntando copia de su DNI o documento equivalente.\u00a0 Asimismo, y especialmente si considera que no ha obtenido satisfacci\u00f3n plena en el ejercicio de sus derechos, podr\u00e1 presentar una reclamaci\u00f3n ante la autoridad nacional de control dirigi\u00e9ndose a estos efectos a la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, C\/ Jorge Juan, 6 \u2013 28001 Madrid.<\/p>\r\n<p>Asimismo, solicitamos su autorizaci\u00f3n en el formulario para ofrecerle productos y servicios relacionados con los contratados y fidelizarle como cliente.<\/p>\r\n<h2>CONDICIONES DE USO DEL PORTAL PARA LOS USUARIOS.<\/h2>\r\n<p>El acceso al presente Sitio es gratuito salvo en lo relativo al coste de la conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso contratado por los usuarios.<\/p>\r\n<p>Queda expresamente prohibido el uso del Sitio con fines lesivos de bienes o intereses de CRISTINA LUNA o de terceros o que de cualquier otra forma sobrecarguen, da\u00f1en o inutilicen las redes, servidores y dem\u00e1s equipos inform\u00e1ticos (hardware) o productos y aplicaciones inform\u00e1ticas (software) de CRISTINA LUNA, o de terceros.<\/p>\r\n<p>En el caso de que el Usuario tuviera conocimiento de que los Sitios enlazados remiten a p\u00e1ginas cuyos contenidos o servicios son il\u00edcitos, nocivos, denigrantes, violentos o contrarios a la moral le agradecer\u00edamos que se pusiera en contacto con CRISTINA LUNA.<\/p>\r\n<h2>LEGISLACI\u00d3N.<\/h2>\r\n<p>El presente Aviso Legal se rige en todos y cada uno de sus extremos por la legislaci\u00f3n espa\u00f1ola.<\/p>\r\n<h2>CONTACTE CON NOSOTROS.<\/h2>\r\n<p>Si tiene Ud. cualquier pregunta sobre las condiciones reflejadas en este Aviso Legal, o si le gustar\u00eda hacer cualquier sugerencia o recomendaci\u00f3n, por favor dir\u00edjase a nosotros a trav\u00e9s de la siguiente direcci\u00f3n de correo electr\u00f3nico: hola@chrispeluqueria.com<\/p>\r\n<p>LOS USUARIOS DE NUESTRA WEB SON CONOCEDORES DE TODO LO EXPUESTO Y LO ACEPTAN VOLUNTARIAMENTE, ACEPTANDO EL AVISO LEGAL, POL\u00cdTICA DE COOKIES Y POL\u00cdTICA DE PROTECCI\u00d3N DE DATOS DE CAR\u00c1CTER PERSONAL.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INTRODUCCI\u00d3N. El presente documento tiene como finalidad el establecer y regular las normas de uso del Sitio www.chrispeluqueria.com entendiendo por Sitio todas las p\u00e1ginas y sus contenidos propiedad de CRISTINA LUNA a las cuales se accede a trav\u00e9s del dominio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/chrispeluqueria.com\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrispeluqueria.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chrispeluqueria.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chrispeluqueria.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chrispeluqueria.com\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":4,"href":"https:\/\/chrispeluqueria.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":5917,"href":"https:\/\/chrispeluqueria.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/5917"}],"wp:attachment":[{"href":"https:\/\/chrispeluqueria.com\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}